{"id":7153,"date":"2021-10-08T22:25:50","date_gmt":"2021-10-08T21:25:50","guid":{"rendered":"https:\/\/www.adele-schoenheitssalon.at\/chi-siamo\/"},"modified":"2026-04-10T00:04:35","modified_gmt":"2026-04-09T23:04:35","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/www.adele-schoenheitssalon.at\/it\/chi-siamo\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7153\" class=\"elementor elementor-7153 elementor-395\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55a1da3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"55a1da3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40d338f\" data-id=\"40d338f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-075b3a1 elementor-widget elementor-widget-image\" data-id=\"075b3a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"750\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2026\/04\/adele-luxury-750.jpg\" class=\"attachment-full size-full wp-image-9336\" alt=\"\" srcset=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2026\/04\/adele-luxury-750.jpg 1920w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2026\/04\/adele-luxury-750-300x117.jpg 300w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2026\/04\/adele-luxury-750-1024x400.jpg 1024w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2026\/04\/adele-luxury-750-768x300.jpg 768w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2026\/04\/adele-luxury-750-1536x600.jpg 1536w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2026\/04\/adele-luxury-750-1568x613.jpg 1568w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" style=\"width:100%;height:39.06%;max-width:1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d14537d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d14537d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3f2b304e\" data-id=\"3f2b304e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bb86f63 elementor-widget elementor-widget-text-editor\" data-id=\"6bb86f63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il nostro salone<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1579858f elementor-widget elementor-widget-heading\" data-id=\"1579858f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Estetica<br> nel cuore di Vienna<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69957438 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"69957438\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e04f529\" data-id=\"e04f529\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63d3377d elementor-widget elementor-widget-image\" data-id=\"63d3377d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1284\" height=\"1635\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-2.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1099\" alt=\"\" srcset=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-2.jpg 1284w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-2-236x300.jpg 236w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-2-804x1024.jpg 804w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-2-768x978.jpg 768w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-2-1206x1536.jpg 1206w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-2-600x764.jpg 600w\" sizes=\"(max-width: 1284px) 100vw, 1284px\" style=\"width:100%;height:127.34%;max-width:1284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3057718b elementor-widget elementor-widget-text-editor\" data-id=\"3057718b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ci riforniamo delle pi\u00f9 recenti innovazioni, prodotti e attrezzature per le vostre esigenze estetiche.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-52e8414d\" data-id=\"52e8414d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4423e5f5 elementor-widget elementor-widget-text-editor\" data-id=\"4423e5f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Solo trattamenti di alta qualit\u00e0 eseguiti da professionisti di prima classe in un unico luogo<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a63dab8 elementor-widget elementor-widget-image\" data-id=\"5a63dab8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-1.jpg\" title=\"\" alt=\"\" class=\"elementor-animation-grow\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ef5e969 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ef5e969\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-421c4016\" data-id=\"421c4016\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66d648 elementor-widget elementor-widget-image\" data-id=\"66d648\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1071\" height=\"1344\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-3.jpg\" class=\"attachment-full size-full wp-image-1106\" alt=\"\" srcset=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-3.jpg 1071w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-3-239x300.jpg 239w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-3-816x1024.jpg 816w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-3-768x964.jpg 768w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuerk-3-600x753.jpg 600w\" sizes=\"(max-width: 1071px) 100vw, 1071px\" style=\"width:100%;height:125.49%;max-width:1071px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3790d7ad\" data-id=\"3790d7ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61aa62c2 elementor-widget elementor-widget-image\" data-id=\"61aa62c2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1200\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuek.jpg\" class=\"attachment-full size-full wp-image-1097\" alt=\"\" srcset=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuek.jpg 960w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuek-240x300.jpg 240w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuek-819x1024.jpg 819w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuek-768x960.jpg 768w, https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2021\/11\/Adile-Oeztuek-600x750.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" style=\"width:100%;height:125%;max-width:960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41b9e581 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"41b9e581\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:54}},&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f29b25c\" data-id=\"1f29b25c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74d49b9f elementor-widget elementor-widget-heading\" data-id=\"74d49b9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cosa facciamo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-353551b3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"353551b3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dc106ab elementor-widget elementor-widget-heading\" data-id=\"6dc106ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Il salone di bellezza ADELE \u00e8 una destinazione di bellezza unica a Vienna che copre tutte le esigenze di bellezza dalla testa ai piedi. Il vostro viaggio inizia quando entrate nel nostro ambiente rilassante, dall'arredamento chic e dall'atmosfera accogliente e su misura per voi. All'interno, il nostro team di professionisti offre consigli esperti e trattamenti su misura, con un approccio molto attento e personale che vi far\u00e0 sentire coccolati e rivitalizzati ai massimi livelli.<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac2782c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ac2782c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1758cb0\" data-id=\"1758cb0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11688db elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"11688db\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2022\/02\/Kosmetikstudio-Wien-1090-Behandlungsraum.jpg\" title=\"Kosmetikstudio-Wien-1090-Behandlungsraum\" alt=\"Kosmetikstudio Wien 1090, Beauty Salon Wien 1090\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0363ea6 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"0363ea6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/2022\/02\/Kosmetikstudio-Wien-1090-Behandlungsraum.jpg\" title=\"Kosmetikstudio-Wien-1090-Behandlungsraum\" alt=\"Kosmetikstudio Wien 1090, Beauty Salon Wien 1090\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a074b2b\" data-id=\"a074b2b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-320e79f elementor-widget elementor-widget-heading\" data-id=\"320e79f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Professionale<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0167e8e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0167e8e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac0224b elementor-widget elementor-widget-heading\" data-id=\"ac0224b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><b>Philings:<\/b> Assistente Maestro<br><b>Phibrows:<\/b> Artista<br><b>Sopracciglia di polvere:<\/b> Artista<br><b>Phicontour:<\/b> Artista reale<br> \n<b>Phinjection:<\/b> Artista<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17ca049 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"17ca049\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/PowderBrows-Zertifikat-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"PowderBrows-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/PhiLings-Zertifikat-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"PhiLings-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/PhiContour-Zertifikat-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"PhiContour-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/PhiBright-Microneedling-Zertifikat-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"PhiBright-Microneedling-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/Philings-Craft-Master-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"Philings-Craft-Master\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/PhInjection-Zertifikat2-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"PhInjection-Zertifikat2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/BB-Glow-Zertifikat-q7wajzuavjumuwzwh2cm6gbu5q4mkls3mqz07f0gsg.jpg\" alt=\"BB-Glow-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/BBC-Glow-Zertifikat-q7wajzuavjumuwzwh2cm6gbu5q4mkls3mqz07f0gsg.jpg\" alt=\"BBC-Glow-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/Lash-Extension-Zertifikat-q7wajzuavjumuwzwh2cm6gbu5q4mkls3mqz07f0gsg.jpg\" alt=\"Lash-Extension-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/Lash-Brow-Lifting-Laminierung-q7wajzuavjumuwzwh2cm6gbu5q4mkls3mqz07f0gsg.jpg\" alt=\"Lash-Brow-Lifting-Laminierung\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/SkinCare-Zertifikat-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"SkinCare-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 di 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/PowderBrows-Zertifikat-q7wak0s52dvx6iyjbkr8qy3ar3zzsavtyvmhooz2m8.jpg\" alt=\"PowderBrows-Zertifikat\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-00ba9f9\" data-id=\"00ba9f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1981a6d elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"1981a6d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/LashFest-2019-Teilnahme-q7wajzuavjv7bic6t512pk5ujkktuhra88gu8djf28.jpg\" alt=\"LashFest-2019-Teilnahme\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/LashFest2019-Platz-2-Brows-q7wajzuavjv7bic6t512pk5ujkktuhra88gu8djf28.jpg\" alt=\"LashFest2019-Platz-2-Brows\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/Lash-Extension-Training-q7wajzuavjv7bic6t512pk5ujkktuhra88gu8djf28.jpg\" alt=\"Lash-Extension-Training\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/Microblading-Zertifikat-q7wajzuavjv7bic6t512pk5ujkktuhra88gu8djf28.jpg\" alt=\"Microblading-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/Soprano-Ice-Zertifikat-q7wak0s52dwhn4atnnfpa1xb4yg726v0kd4bpni0w0.jpg\" alt=\"Soprano-Ice-Zertifikat\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.adele-schoenheitssalon.at\/wp-content\/uploads\/elementor\/thumbs\/LashFest-2019-Teilnahme-q7wajzuavjv7bic6t512pk5ujkktuhra88gu8djf28.jpg\" alt=\"LashFest-2019-Teilnahme\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14cb8d49 elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"14cb8d49\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-35cb0254\" data-id=\"35cb0254\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-cdd802a\" data-id=\"cdd802a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d428ec elementor-invisible elementor-widget elementor-widget-testimonial\" data-id=\"8d428ec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><p>\"La bellezza \u00e8 nei dettagli. Siate belli come voi stessi\".<\/p>\n<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Adile \u00d6zt\u00fcrk<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">&amp;nbsp&amp;nbsp&amp;nbspProprietario<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6ebaea8b\" data-id=\"6ebaea8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Il nostro salone Estetica nel cuore di Vienna Ci riforniamo delle pi\u00f9 recenti innovazioni, prodotti e attrezzature per le vostre esigenze estetiche. Solo trattamenti di alta qualit\u00e0 eseguiti da professionisti di prima classe in un unico luogo Cosa facciamo Il salone di bellezza ADELE \u00e8 una destinazione di bellezza unica a Vienna che copre tutte&hellip; <a class=\"more-link\" href=\"https:\/\/www.adele-schoenheitssalon.at\/it\/chi-siamo\/\">Continua a leggere <span class=\"screen-reader-text\">Chi siamo<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-7153","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/pages\/7153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/comments?post=7153"}],"version-history":[{"count":2,"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/pages\/7153\/revisions"}],"predecessor-version":[{"id":9348,"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/pages\/7153\/revisions\/9348"}],"wp:attachment":[{"href":"https:\/\/www.adele-schoenheitssalon.at\/it\/wp-json\/wp\/v2\/media?parent=7153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}